{"id":60,"count":3,"description":"","link":"https:\/\/themar-trucks.com\/de\/category\/auflieger\/","name":"Auflieger","slug":"auflieger","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Auflieger Archieven - Themar Trucks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/themar-trucks.com\/de\/category\/auflieger\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auflieger Archieven\" \/>\n<meta property=\"og:url\" content=\"https:\/\/themar-trucks.com\/de\/category\/auflieger\/\" \/>\n<meta property=\"og:site_name\" content=\"Themar Trucks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Themartrucks\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/de\\\/category\\\/auflieger\\\/\",\"url\":\"https:\\\/\\\/themar-trucks.com\\\/de\\\/category\\\/auflieger\\\/\",\"name\":\"Auflieger Archieven - Themar Trucks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/de\\\/category\\\/auflieger\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/de\\\/category\\\/auflieger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/themar-trucks.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auflieger\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/#website\",\"url\":\"https:\\\/\\\/themar-trucks.com\\\/\",\"name\":\"Themar Trucks\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/themar-trucks.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/#organization\",\"name\":\"THEMAR TRUCKS NV\",\"url\":\"https:\\\/\\\/themar-trucks.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/themar-trucks.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Logo_ThemarTrucks.png\",\"contentUrl\":\"https:\\\/\\\/themar-trucks.com\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/Logo_ThemarTrucks.png\",\"width\":312,\"height\":47,\"caption\":\"THEMAR TRUCKS NV\"},\"image\":{\"@id\":\"https:\\\/\\\/themar-trucks.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/themartrucks\\\/\",\"https:\\\/\\\/x.com\\\/Themartrucks\",\"https:\\\/\\\/www.instagram.com\\\/themartrucks\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@ThemarTrucksnv\"],\"description\":\"Themar Trucks is een Belgische vrachtwagendealer en is sinds 1996 een gevestigde waarde langsheen de A12 in Willebroek. Wij zijn gespecialiseerd in de aankoop en verkoop van 2dehands vrachtwagens van alle types, soorten en bouwjaren zoals trekkers, vrachtwagens met containersystemen en kranen, kippers en opleggers. Daarnaast hebben we ook een aanbod van 2dehands Bouwmachines zoals graafmachines en wielladers van verschillende merken. Onze klanten situeren zich in diverse sectoren (zoals de bouw \u2013en transportsectoren) en zijn wereldwijd verspreid. Ons aanbod wordt dagelijks up-to-date gehouden op onze website. We focussen ons op marktconforme prijzen en een vlotte administratieve afhandeling.\",\"email\":\"info@themar-trucks.com\",\"telephone\":\"+3238663663\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Auflieger Archieven - Themar Trucks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/themar-trucks.com\/de\/category\/auflieger\/","og_locale":"de_DE","og_type":"article","og_title":"Auflieger Archieven","og_url":"https:\/\/themar-trucks.com\/de\/category\/auflieger\/","og_site_name":"Themar Trucks","twitter_card":"summary_large_image","twitter_site":"@Themartrucks","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/themar-trucks.com\/de\/category\/auflieger\/","url":"https:\/\/themar-trucks.com\/de\/category\/auflieger\/","name":"Auflieger Archieven - Themar Trucks","isPartOf":{"@id":"https:\/\/themar-trucks.com\/#website"},"breadcrumb":{"@id":"https:\/\/themar-trucks.com\/de\/category\/auflieger\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/themar-trucks.com\/de\/category\/auflieger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/themar-trucks.com\/de\/"},{"@type":"ListItem","position":2,"name":"Auflieger"}]},{"@type":"WebSite","@id":"https:\/\/themar-trucks.com\/#website","url":"https:\/\/themar-trucks.com\/","name":"Themar Trucks","description":"","publisher":{"@id":"https:\/\/themar-trucks.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/themar-trucks.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/themar-trucks.com\/#organization","name":"THEMAR TRUCKS NV","url":"https:\/\/themar-trucks.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/themar-trucks.com\/#\/schema\/logo\/image\/","url":"https:\/\/themar-trucks.com\/wp-content\/uploads\/2018\/02\/Logo_ThemarTrucks.png","contentUrl":"https:\/\/themar-trucks.com\/wp-content\/uploads\/2018\/02\/Logo_ThemarTrucks.png","width":312,"height":47,"caption":"THEMAR TRUCKS NV"},"image":{"@id":"https:\/\/themar-trucks.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/themartrucks\/","https:\/\/x.com\/Themartrucks","https:\/\/www.instagram.com\/themartrucks\/","https:\/\/www.youtube.com\/@ThemarTrucksnv"],"description":"Themar Trucks is een Belgische vrachtwagendealer en is sinds 1996 een gevestigde waarde langsheen de A12 in Willebroek. Wij zijn gespecialiseerd in de aankoop en verkoop van 2dehands vrachtwagens van alle types, soorten en bouwjaren zoals trekkers, vrachtwagens met containersystemen en kranen, kippers en opleggers. Daarnaast hebben we ook een aanbod van 2dehands Bouwmachines zoals graafmachines en wielladers van verschillende merken. Onze klanten situeren zich in diverse sectoren (zoals de bouw \u2013en transportsectoren) en zijn wereldwijd verspreid. Ons aanbod wordt dagelijks up-to-date gehouden op onze website. We focussen ons op marktconforme prijzen en een vlotte administratieve afhandeling.","email":"info@themar-trucks.com","telephone":"+3238663663"}]}},"_links":{"self":[{"href":"https:\/\/themar-trucks.com\/de\/wp-json\/wp\/v2\/categories\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/themar-trucks.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/themar-trucks.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}]}}